{"id":11,"count":5,"description":"","link":"https:\/\/discover-andalusia.com\/pl\/category\/sevilla\/","name":"Sewilla","slug":"sevilla","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/discover-andalusia.com\/pl\/wp-json\/wp\/v2\/categories\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discover-andalusia.com\/pl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/discover-andalusia.com\/pl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/discover-andalusia.com\/pl\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}