{"id":16,"count":4,"description":"","link":"https:\/\/discover-andalusia.com\/pt\/category\/viajar\/","name":"Viagem","slug":"travel","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/discover-andalusia.com\/pt\/wp-json\/wp\/v2\/categories\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discover-andalusia.com\/pt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/discover-andalusia.com\/pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/discover-andalusia.com\/pt\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}